{"id":4935,"date":"2025-06-19T04:36:44","date_gmt":"2025-06-19T02:36:44","guid":{"rendered":"https:\/\/stopalzheimer.be\/?p=4935"},"modified":"2025-06-19T04:36:45","modified_gmt":"2025-06-19T02:36:45","slug":"soutien-stop-alzheimer","status":"publish","type":"post","link":"https:\/\/stopalzheimer.be\/fr\/soutien-stop-alzheimer\/","title":{"rendered":"L\u2019\u00c9cole Royale Militaire remet un don de 52.161\u202f\u20ac \u00e0 Stop Alzheimer"},"content":{"rendered":"<h2 class=\"wp-block-heading\">L\u2019\u00c9cole Royale Militaire remet un don de 52.161\u202f\u20ac \u00e0 Stop Alzheimer<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Bruxelles, le 18 juin 2025<\/strong> \u2013 C\u2019est avec une immense reconnaissance que notre Fondation a re\u00e7u un don de <strong>52.161 euros<\/strong> de la part de l\u2019<a href=\"https:\/\/www.rma.ac.be\/fr\">\u00c9cole Royale Militaire (ERM)<\/a>, en soutien \u00e0 la recherche scientifique contre la maladie d\u2019Alzheimer et les maladies apparent\u00e9es. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Choisie comme <strong>cause soutenue par la 161e promotion en Sciences Sociales et Militaires<\/strong>, les cadets se sont mobilis\u00e9s &#8211; d\u00e8s septembre 2024 &#8211; avec enthousiasme pour organiser de nombreuses actions et initiatives, toutes guid\u00e9es par un objectif commun : collecter un maximum de fonds pour faire avancer la recherche.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le fruit de leur engagement : une somme remarquable, officiellement remise le 18 juin lors d\u2019une c\u00e9r\u00e9monie solennelle en pr\u00e9sence du G\u00e9n\u00e9ral De Potter, qui a tenu \u00e0 saluer personnellement la solidarit\u00e9 et l\u2019implication des \u00e9tudiants.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ensemble, faisons la diff\u00e9rence<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le soutien de l\u2019ERM repr\u00e9sente un encouragement pr\u00e9cieux pour les projets de recherche financ\u00e9s par Stop Alzheimer. Dans un contexte o\u00f9 le nombre de personnes atteintes de la maladie augmente chaque ann\u00e9e, chaque don compte et contribue \u00e0 faire avancer la science.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous adressons nos plus sinc\u00e8res remerciements \u00e0 l\u2019\u00c9cole Royale Militaire, \u00e0 tous les \u00e9tudiants impliqu\u00e9s, et tout particuli\u00e8rement \u00e0 Ruben Bel pour son r\u00f4le moteur dans cette initiative. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"578\" src=\"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/06\/pro-Wd1hoOD3-1024x578.jpeg\" alt=\"\" class=\"wp-image-4923\" srcset=\"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/06\/pro-Wd1hoOD3-1024x578.jpeg 1024w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/06\/pro-Wd1hoOD3-300x169.jpeg 300w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/06\/pro-Wd1hoOD3-768x434.jpeg 768w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/06\/pro-Wd1hoOD3-1536x867.jpeg 1536w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/06\/pro-Wd1hoOD3-2048x1157.jpeg 2048w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/06\/pro-Wd1hoOD3-18x10.jpeg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00c9cole Royale Militaire remet un don de 52.161\u202f\u20ac \u00e0 Stop Alzheimer Bruxelles, le 18 juin 2025 \u2013 C\u2019est avec une immense reconnaissance que notre Fondation a re\u00e7u un don de 52.161 euros de la part de l\u2019\u00c9cole Royale Militaire (ERM), en soutien \u00e0 la recherche scientifique contre la maladie d\u2019Alzheimer et les maladies apparent\u00e9es. Choisie [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4923,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"locatie":[],"class_list":["post-4935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-getuigenissen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019\u00c9cole Royale Militaire remet un don de 52.161\u202f\u20ac \u00e0 Stop Alzheimer - Stop Alzheimer<\/title>\n<meta name=\"description\" content=\"Stop Alzheimer a re\u00e7u un don de 52.161\u202f\u20ac de l\u2019\u00c9cole Royale Militaire. Une mobilisation exemplaire pour soutenir la recherche contre Alzheimer\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stopalzheimer.be\/fr\/soutien-stop-alzheimer\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019\u00c9cole Royale Militaire remet un don de 52.161\u202f\u20ac \u00e0 Stop Alzheimer - Stop Alzheimer\" \/>\n<meta property=\"og:description\" content=\"Stop Alzheimer a re\u00e7u un don de 52.161\u202f\u20ac de l\u2019\u00c9cole Royale Militaire. Une mobilisation exemplaire pour soutenir la recherche contre Alzheimer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stopalzheimer.be\/fr\/soutien-stop-alzheimer\/\" \/>\n<meta property=\"og:site_name\" content=\"Stop Alzheimer\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/StichtingAlzheimerOnderzoek\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-19T02:36:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-19T02:36:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/06\/pro-Wd1hoOD3-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1446\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lucie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/nl\\\/soutien-stop-alzheimer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/nl\\\/soutien-stop-alzheimer\\\/\"},\"author\":{\"name\":\"Lucie\",\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/#\\\/schema\\\/person\\\/a4bfa7bb02bcf39e27ec3b315c293e22\"},\"headline\":\"L\u2019\u00c9cole Royale Militaire remet un don de 52.161\u202f\u20ac \u00e0 Stop Alzheimer\",\"datePublished\":\"2025-06-19T02:36:44+00:00\",\"dateModified\":\"2025-06-19T02:36:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/nl\\\/soutien-stop-alzheimer\\\/\"},\"wordCount\":234,\"publisher\":{\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/nl\\\/soutien-stop-alzheimer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stopalzheimer.be\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/pro-Wd1hoOD3-scaled.jpeg\",\"articleSection\":[\"Getuigenissen\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/nl\\\/soutien-stop-alzheimer\\\/\",\"url\":\"https:\\\/\\\/stopalzheimer.be\\\/nl\\\/soutien-stop-alzheimer\\\/\",\"name\":\"L\u2019\u00c9cole Royale Militaire remet un don de 52.161\u202f\u20ac \u00e0 Stop Alzheimer - Stop Alzheimer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/nl\\\/soutien-stop-alzheimer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/nl\\\/soutien-stop-alzheimer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stopalzheimer.be\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/pro-Wd1hoOD3-scaled.jpeg\",\"datePublished\":\"2025-06-19T02:36:44+00:00\",\"dateModified\":\"2025-06-19T02:36:45+00:00\",\"description\":\"Stop Alzheimer a re\u00e7u un don de 52.161\u202f\u20ac de l\u2019\u00c9cole Royale Militaire. Une mobilisation exemplaire pour soutenir la recherche contre Alzheimer\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/nl\\\/soutien-stop-alzheimer\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stopalzheimer.be\\\/nl\\\/soutien-stop-alzheimer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/nl\\\/soutien-stop-alzheimer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stopalzheimer.be\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/pro-Wd1hoOD3-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/stopalzheimer.be\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/pro-Wd1hoOD3-scaled.jpeg\",\"width\":2560,\"height\":1446},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/nl\\\/soutien-stop-alzheimer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stopalzheimer.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019\u00c9cole Royale Militaire remet un don de 52.161\u202f\u20ac \u00e0 Stop Alzheimer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/\",\"name\":\"Stop Alzheimer\",\"description\":\"Stichting Alzheimer Onderzoek\",\"publisher\":{\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/#organization\",\"name\":\"Stop Alzheimer\",\"url\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stopalzheimer.be\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/241021_Alzheimer_logoNL_NEW.png\",\"contentUrl\":\"https:\\\/\\\/stopalzheimer.be\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/241021_Alzheimer_logoNL_NEW.png\",\"width\":2362,\"height\":515,\"caption\":\"Stop Alzheimer\"},\"image\":{\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/StichtingAlzheimerOnderzoek\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@stichtingalzheimeronderzoe3860\\\/videos\",\"https:\\\/\\\/be.linkedin.com\\\/in\\\/stichting-alzheimer-onderzoek-fondation-recherche-alzheimer-8760b61a4\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/#\\\/schema\\\/person\\\/a4bfa7bb02bcf39e27ec3b315c293e22\",\"name\":\"Lucie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2cabf71da3f66ce28610368d66eab36ec2a054b07526e0376fc3565112668b7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2cabf71da3f66ce28610368d66eab36ec2a054b07526e0376fc3565112668b7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2cabf71da3f66ce28610368d66eab36ec2a054b07526e0376fc3565112668b7?s=96&d=mm&r=g\",\"caption\":\"Lucie\"},\"url\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/author\\\/lucie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019\u00c9cole Royale Militaire remet un don de 52.161\u202f\u20ac \u00e0 Stop Alzheimer - Stop Alzheimer","description":"Stop Alzheimer a re\u00e7u un don de 52.161\u202f\u20ac de l\u2019\u00c9cole Royale Militaire. Une mobilisation exemplaire pour soutenir la recherche contre Alzheimer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stopalzheimer.be\/fr\/soutien-stop-alzheimer\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019\u00c9cole Royale Militaire remet un don de 52.161\u202f\u20ac \u00e0 Stop Alzheimer - Stop Alzheimer","og_description":"Stop Alzheimer a re\u00e7u un don de 52.161\u202f\u20ac de l\u2019\u00c9cole Royale Militaire. Une mobilisation exemplaire pour soutenir la recherche contre Alzheimer","og_url":"https:\/\/stopalzheimer.be\/fr\/soutien-stop-alzheimer\/","og_site_name":"Stop Alzheimer","article_publisher":"https:\/\/www.facebook.com\/StichtingAlzheimerOnderzoek\/","article_published_time":"2025-06-19T02:36:44+00:00","article_modified_time":"2025-06-19T02:36:45+00:00","og_image":[{"width":2560,"height":1446,"url":"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/06\/pro-Wd1hoOD3-scaled.jpeg","type":"image\/jpeg"}],"author":"Lucie","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Lucie","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stopalzheimer.be\/nl\/soutien-stop-alzheimer\/#article","isPartOf":{"@id":"https:\/\/stopalzheimer.be\/nl\/soutien-stop-alzheimer\/"},"author":{"name":"Lucie","@id":"https:\/\/stopalzheimer.be\/fr\/#\/schema\/person\/a4bfa7bb02bcf39e27ec3b315c293e22"},"headline":"L\u2019\u00c9cole Royale Militaire remet un don de 52.161\u202f\u20ac \u00e0 Stop Alzheimer","datePublished":"2025-06-19T02:36:44+00:00","dateModified":"2025-06-19T02:36:45+00:00","mainEntityOfPage":{"@id":"https:\/\/stopalzheimer.be\/nl\/soutien-stop-alzheimer\/"},"wordCount":234,"publisher":{"@id":"https:\/\/stopalzheimer.be\/fr\/#organization"},"image":{"@id":"https:\/\/stopalzheimer.be\/nl\/soutien-stop-alzheimer\/#primaryimage"},"thumbnailUrl":"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/06\/pro-Wd1hoOD3-scaled.jpeg","articleSection":["Getuigenissen"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/stopalzheimer.be\/nl\/soutien-stop-alzheimer\/","url":"https:\/\/stopalzheimer.be\/nl\/soutien-stop-alzheimer\/","name":"L\u2019\u00c9cole Royale Militaire remet un don de 52.161\u202f\u20ac \u00e0 Stop Alzheimer - Stop Alzheimer","isPartOf":{"@id":"https:\/\/stopalzheimer.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stopalzheimer.be\/nl\/soutien-stop-alzheimer\/#primaryimage"},"image":{"@id":"https:\/\/stopalzheimer.be\/nl\/soutien-stop-alzheimer\/#primaryimage"},"thumbnailUrl":"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/06\/pro-Wd1hoOD3-scaled.jpeg","datePublished":"2025-06-19T02:36:44+00:00","dateModified":"2025-06-19T02:36:45+00:00","description":"Stop Alzheimer a re\u00e7u un don de 52.161\u202f\u20ac de l\u2019\u00c9cole Royale Militaire. Une mobilisation exemplaire pour soutenir la recherche contre Alzheimer","breadcrumb":{"@id":"https:\/\/stopalzheimer.be\/nl\/soutien-stop-alzheimer\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stopalzheimer.be\/nl\/soutien-stop-alzheimer\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stopalzheimer.be\/nl\/soutien-stop-alzheimer\/#primaryimage","url":"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/06\/pro-Wd1hoOD3-scaled.jpeg","contentUrl":"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/06\/pro-Wd1hoOD3-scaled.jpeg","width":2560,"height":1446},{"@type":"BreadcrumbList","@id":"https:\/\/stopalzheimer.be\/nl\/soutien-stop-alzheimer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stopalzheimer.be\/"},{"@type":"ListItem","position":2,"name":"L\u2019\u00c9cole Royale Militaire remet un don de 52.161\u202f\u20ac \u00e0 Stop Alzheimer"}]},{"@type":"WebSite","@id":"https:\/\/stopalzheimer.be\/fr\/#website","url":"https:\/\/stopalzheimer.be\/fr\/","name":"Stop Alzheimer","description":"Fondation Recherche Alzheimer","publisher":{"@id":"https:\/\/stopalzheimer.be\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stopalzheimer.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stopalzheimer.be\/fr\/#organization","name":"Stop Alzheimer","url":"https:\/\/stopalzheimer.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stopalzheimer.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/04\/241021_Alzheimer_logoNL_NEW.png","contentUrl":"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/04\/241021_Alzheimer_logoNL_NEW.png","width":2362,"height":515,"caption":"Stop Alzheimer"},"image":{"@id":"https:\/\/stopalzheimer.be\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/StichtingAlzheimerOnderzoek\/","https:\/\/www.youtube.com\/@stichtingalzheimeronderzoe3860\/videos","https:\/\/be.linkedin.com\/in\/stichting-alzheimer-onderzoek-fondation-recherche-alzheimer-8760b61a4"]},{"@type":"Person","@id":"https:\/\/stopalzheimer.be\/fr\/#\/schema\/person\/a4bfa7bb02bcf39e27ec3b315c293e22","name":"Lucie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a2cabf71da3f66ce28610368d66eab36ec2a054b07526e0376fc3565112668b7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2cabf71da3f66ce28610368d66eab36ec2a054b07526e0376fc3565112668b7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2cabf71da3f66ce28610368d66eab36ec2a054b07526e0376fc3565112668b7?s=96&d=mm&r=g","caption":"Lucie"},"url":"https:\/\/stopalzheimer.be\/fr\/author\/lucie\/"}]}},"_links":{"self":[{"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/posts\/4935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/comments?post=4935"}],"version-history":[{"count":1,"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/posts\/4935\/revisions"}],"predecessor-version":[{"id":4936,"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/posts\/4935\/revisions\/4936"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/media\/4923"}],"wp:attachment":[{"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/media?parent=4935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/categories?post=4935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/tags?post=4935"},{"taxonomy":"locatie","embeddable":true,"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/locatie?post=4935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}