{"id":4232,"date":"2025-01-15T14:20:31","date_gmt":"2025-01-15T13:20:31","guid":{"rendered":"https:\/\/stopalzheimer.be\/?p=4232"},"modified":"2026-01-29T09:25:49","modified_gmt":"2026-01-29T08:25:49","slug":"velomediane-2026-stop-alzheimer","status":"publish","type":"post","link":"https:\/\/stopalzheimer.be\/fr\/velomediane-2026-stop-alzheimer\/","title":{"rendered":"V\u00e9lom\u00e9diane au profit de la recherche contre Alzheimer"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Rejoignez-nous pour la 4\u1d49 \u00e9dition de la V\u00e9lom\u00e9diane au profit de la recherche contre Alzheimer !<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ce 22 ao\u00fbt 2026, nous avons le plaisir d\u2019\u00eatre associ\u00e9s \u00e0 nouveaux \u00e0 la mythique V\u00e9lom\u00e9diane Claudy Criqui\u00e9lion, la plus ancienne cyclosportive de Belgique. Cet \u00e9v\u00e9nement est bien plus qu\u2019un d\u00e9fi sportif\u202f: c\u2019est une occasion unique de p\u00e9daler ensemble pour une cause essentielle, vaincre la maladie d\u2019Alzheimer.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"5955\" src=\"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_OP2_00455-1024x682.jpg\" alt=\"\" class=\"wp-image-5955\" srcset=\"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_OP2_00455-1024x682.jpg 1024w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_OP2_00455-300x200.jpg 300w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_OP2_00455-768x512.jpg 768w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_OP2_00455-1536x1024.jpg 1536w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_OP2_00455-18x12.jpg 18w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_OP2_00455.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"5954\" src=\"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_ALN1_02590-1024x682.jpg\" alt=\"\" class=\"wp-image-5954\" srcset=\"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_ALN1_02590-1024x682.jpg 1024w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_ALN1_02590-300x200.jpg 300w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_ALN1_02590-768x512.jpg 768w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_ALN1_02590-1536x1024.jpg 1536w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_ALN1_02590-18x12.jpg 18w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_ALN1_02590.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En 2025, gr\u00e2ce \u00e0 la mobilisation exceptionnelle des participants, nous avons r\u00e9colt\u00e9 <strong><a href=\"https:\/\/stopalzheimer.be\/fr\/velomediane2025-stop-alzheimer\/\" type=\"link\" id=\"https:\/\/stopalzheimer.be\/fr\/velomediane2025-stop-alzheimer\/\">12.335\u20ac pour la recherche<\/a>. <\/strong>Cette ann\u00e9e, nous esp\u00e9rons bien avec votre soutien battre ce record !<\/p>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Comment participer ? <\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Inscrivez-vous d\u00e8s aujourd\u2019hui<\/strong> sur <a href=\"https:\/\/www.velomediane.com\/inscription-velomed\/\">www.v\u00e9lom\u00e9diane.com<\/a> : Avec des parcours de 86 \u00e0 172 km, cet \u00e9v\u00e9nement vous fait traverser les plus beaux reliefs de la r\u00e9gion de la Roche-en-Ardenne.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lors de votre inscription, <strong>commandez le maillot officiel<\/strong> : Portez fi\u00e8rement les couleurs de la V\u00e9lom\u00e9diane x Stop Alzheimer\u202f! Vendu au prix de 60\u20ac, les b\u00e9n\u00e9fices de chaque vente sont enti\u00e8rement revers\u00e9s \u00e0 la recherche.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Cr\u00e9ez votre page de collecte<\/strong> : Faites de votre d\u00e9fi une aventure collective et solidaire\u202fsur <a href=\"https:\/\/action.stopalzheimer.be\/project\/velomediane-2026?locale=fr\" type=\"link\" id=\"https:\/\/action.stopalzheimer.be\/project\/velomediane-2026?locale=fr\">notre plateforme <\/a>et invitez vos proches \u00e0 sponsoriser votre challenge pour soutenir la recherche.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-3e41869c wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/action.stopalzheimer.be\/project\/velomediane-2026?locale=fr\" style=\"background-color:#38499b\">Lancer ma collecte<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"5956\" src=\"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_JKE2_06182-1024x682.jpg\" alt=\"\" class=\"wp-image-5956\" srcset=\"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_JKE2_06182-1024x682.jpg 1024w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_JKE2_06182-300x200.jpg 300w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_JKE2_06182-768x512.jpg 768w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_JKE2_06182-1536x1024.jpg 1536w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_JKE2_06182-18x12.jpg 18w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_JKE2_06182.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"5957\" src=\"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_JKE2_06172-1024x682.jpg\" alt=\"\" class=\"wp-image-5957\" srcset=\"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_JKE2_06172-1024x682.jpg 1024w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_JKE2_06172-300x200.jpg 300w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_JKE2_06172-768x512.jpg 768w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_JKE2_06172-1536x1024.jpg 1536w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_JKE2_06172-18x12.jpg 18w, https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/14017_JKE2_06172.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Infos pratiques<\/h2>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">\ud83c\udfab Pour vous inscrire, rendez-vous <a href=\"https:\/\/www.sqmtime.com\/fr-velomediane\">ici<\/a>. <\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">\ud83d\udcc6 Samedi 22 ao\u00fbt, \u00e0 la Roche en Ardennes.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">\ud83d\udeb4 86, 95, 130 ou 170 km.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">\ud83d\udc5b Tarifs : de 16 \u00e0 30\u20ac (assurances comprises) <\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Pr\u00eat(e) \u00e0 relever le d\u00e9fi\u202f? <\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">\ud83d\udc49<strong><a href=\"https:\/\/www.velomediane.com\/inscription-velomed\/\">Inscrivez-vous maintenant<\/a><\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Rejoignez-nous pour la 4\u1d49 \u00e9dition de la V\u00e9lom\u00e9diane au profit de la recherche contre Alzheimer ! Ce 22 ao\u00fbt 2026, nous avons le plaisir d\u2019\u00eatre associ\u00e9s \u00e0 nouveaux \u00e0 la mythique V\u00e9lom\u00e9diane Claudy Criqui\u00e9lion, la plus ancienne cyclosportive de Belgique. Cet \u00e9v\u00e9nement est bien plus qu\u2019un d\u00e9fi sportif\u202f: c\u2019est une occasion unique de p\u00e9daler ensemble [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4234,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[],"locatie":[],"class_list":["post-4232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenementen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>V\u00e9lom\u00e9diane au profit de la recherche contre Alzheimer - Stop Alzheimer<\/title>\n<meta name=\"description\" content=\"Une occasion unique de p\u00e9daler ensemble au profit de la recherche scientifique pour stopper la maladie d\u2019Alzheimer\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stopalzheimer.be\/fr\/velomediane-2026-stop-alzheimer\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"V\u00e9lom\u00e9diane au profit de la recherche contre Alzheimer - Stop Alzheimer\" \/>\n<meta property=\"og:description\" content=\"Une occasion unique de p\u00e9daler ensemble au profit de la recherche scientifique pour stopper la maladie d\u2019Alzheimer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stopalzheimer.be\/fr\/velomediane-2026-stop-alzheimer\/\" \/>\n<meta property=\"og:site_name\" content=\"Stop Alzheimer\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/StichtingAlzheimerOnderzoek\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-15T13:20:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-29T08:25:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/7627_FMT1LS1_00155.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lucie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/velomediane-2026-stop-alzheimer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/velomediane-2026-stop-alzheimer\\\/\"},\"author\":{\"name\":\"Lucie\",\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/#\\\/schema\\\/person\\\/a4bfa7bb02bcf39e27ec3b315c293e22\"},\"headline\":\"V\u00e9lom\u00e9diane au profit de la recherche contre Alzheimer\",\"datePublished\":\"2025-01-15T13:20:31+00:00\",\"dateModified\":\"2026-01-29T08:25:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/velomediane-2026-stop-alzheimer\\\/\"},\"wordCount\":245,\"publisher\":{\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/velomediane-2026-stop-alzheimer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stopalzheimer.be\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/7627_FMT1LS1_00155.jpg\",\"articleSection\":[\"Evenementen\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/velomediane-2026-stop-alzheimer\\\/\",\"url\":\"https:\\\/\\\/stopalzheimer.be\\\/velomediane-2026-stop-alzheimer\\\/\",\"name\":\"V\u00e9lom\u00e9diane au profit de la recherche contre Alzheimer - Stop Alzheimer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/velomediane-2026-stop-alzheimer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/velomediane-2026-stop-alzheimer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stopalzheimer.be\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/7627_FMT1LS1_00155.jpg\",\"datePublished\":\"2025-01-15T13:20:31+00:00\",\"dateModified\":\"2026-01-29T08:25:49+00:00\",\"description\":\"Une occasion unique de p\u00e9daler ensemble au profit de la recherche scientifique pour stopper la maladie d\u2019Alzheimer\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/velomediane-2026-stop-alzheimer\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stopalzheimer.be\\\/velomediane-2026-stop-alzheimer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/velomediane-2026-stop-alzheimer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stopalzheimer.be\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/7627_FMT1LS1_00155.jpg\",\"contentUrl\":\"https:\\\/\\\/stopalzheimer.be\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/7627_FMT1LS1_00155.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/velomediane-2026-stop-alzheimer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stopalzheimer.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00e9lom\u00e9diane au profit de la recherche contre Alzheimer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/\",\"name\":\"Stop Alzheimer\",\"description\":\"Stichting Alzheimer Onderzoek\",\"publisher\":{\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/#organization\",\"name\":\"Stop Alzheimer\",\"url\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stopalzheimer.be\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/241021_Alzheimer_logoNL_NEW.png\",\"contentUrl\":\"https:\\\/\\\/stopalzheimer.be\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/241021_Alzheimer_logoNL_NEW.png\",\"width\":2362,\"height\":515,\"caption\":\"Stop Alzheimer\"},\"image\":{\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/StichtingAlzheimerOnderzoek\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@stichtingalzheimeronderzoe3860\\\/videos\",\"https:\\\/\\\/be.linkedin.com\\\/in\\\/stichting-alzheimer-onderzoek-fondation-recherche-alzheimer-8760b61a4\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/#\\\/schema\\\/person\\\/a4bfa7bb02bcf39e27ec3b315c293e22\",\"name\":\"Lucie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2cabf71da3f66ce28610368d66eab36ec2a054b07526e0376fc3565112668b7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2cabf71da3f66ce28610368d66eab36ec2a054b07526e0376fc3565112668b7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2cabf71da3f66ce28610368d66eab36ec2a054b07526e0376fc3565112668b7?s=96&d=mm&r=g\",\"caption\":\"Lucie\"},\"url\":\"https:\\\/\\\/stopalzheimer.be\\\/fr\\\/author\\\/lucie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"V\u00e9lom\u00e9diane au profit de la recherche contre Alzheimer - Stop Alzheimer","description":"Une occasion unique de p\u00e9daler ensemble au profit de la recherche scientifique pour stopper la maladie d\u2019Alzheimer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stopalzheimer.be\/fr\/velomediane-2026-stop-alzheimer\/","og_locale":"fr_FR","og_type":"article","og_title":"V\u00e9lom\u00e9diane au profit de la recherche contre Alzheimer - Stop Alzheimer","og_description":"Une occasion unique de p\u00e9daler ensemble au profit de la recherche scientifique pour stopper la maladie d\u2019Alzheimer","og_url":"https:\/\/stopalzheimer.be\/fr\/velomediane-2026-stop-alzheimer\/","og_site_name":"Stop Alzheimer","article_publisher":"https:\/\/www.facebook.com\/StichtingAlzheimerOnderzoek\/","article_published_time":"2025-01-15T13:20:31+00:00","article_modified_time":"2026-01-29T08:25:49+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/7627_FMT1LS1_00155.jpg","type":"image\/jpeg"}],"author":"Lucie","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Lucie","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stopalzheimer.be\/velomediane-2026-stop-alzheimer\/#article","isPartOf":{"@id":"https:\/\/stopalzheimer.be\/velomediane-2026-stop-alzheimer\/"},"author":{"name":"Lucie","@id":"https:\/\/stopalzheimer.be\/fr\/#\/schema\/person\/a4bfa7bb02bcf39e27ec3b315c293e22"},"headline":"V\u00e9lom\u00e9diane au profit de la recherche contre Alzheimer","datePublished":"2025-01-15T13:20:31+00:00","dateModified":"2026-01-29T08:25:49+00:00","mainEntityOfPage":{"@id":"https:\/\/stopalzheimer.be\/velomediane-2026-stop-alzheimer\/"},"wordCount":245,"publisher":{"@id":"https:\/\/stopalzheimer.be\/fr\/#organization"},"image":{"@id":"https:\/\/stopalzheimer.be\/velomediane-2026-stop-alzheimer\/#primaryimage"},"thumbnailUrl":"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/7627_FMT1LS1_00155.jpg","articleSection":["Evenementen"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/stopalzheimer.be\/velomediane-2026-stop-alzheimer\/","url":"https:\/\/stopalzheimer.be\/velomediane-2026-stop-alzheimer\/","name":"V\u00e9lom\u00e9diane au profit de la recherche contre Alzheimer - Stop Alzheimer","isPartOf":{"@id":"https:\/\/stopalzheimer.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stopalzheimer.be\/velomediane-2026-stop-alzheimer\/#primaryimage"},"image":{"@id":"https:\/\/stopalzheimer.be\/velomediane-2026-stop-alzheimer\/#primaryimage"},"thumbnailUrl":"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/7627_FMT1LS1_00155.jpg","datePublished":"2025-01-15T13:20:31+00:00","dateModified":"2026-01-29T08:25:49+00:00","description":"Une occasion unique de p\u00e9daler ensemble au profit de la recherche scientifique pour stopper la maladie d\u2019Alzheimer","breadcrumb":{"@id":"https:\/\/stopalzheimer.be\/velomediane-2026-stop-alzheimer\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stopalzheimer.be\/velomediane-2026-stop-alzheimer\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stopalzheimer.be\/velomediane-2026-stop-alzheimer\/#primaryimage","url":"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/7627_FMT1LS1_00155.jpg","contentUrl":"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/01\/7627_FMT1LS1_00155.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/stopalzheimer.be\/velomediane-2026-stop-alzheimer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stopalzheimer.be\/"},{"@type":"ListItem","position":2,"name":"V\u00e9lom\u00e9diane au profit de la recherche contre Alzheimer"}]},{"@type":"WebSite","@id":"https:\/\/stopalzheimer.be\/fr\/#website","url":"https:\/\/stopalzheimer.be\/fr\/","name":"Stop Alzheimer","description":"Fondation Recherche Alzheimer","publisher":{"@id":"https:\/\/stopalzheimer.be\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stopalzheimer.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/stopalzheimer.be\/fr\/#organization","name":"Stop Alzheimer","url":"https:\/\/stopalzheimer.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stopalzheimer.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/04\/241021_Alzheimer_logoNL_NEW.png","contentUrl":"https:\/\/stopalzheimer.be\/wp-content\/uploads\/2025\/04\/241021_Alzheimer_logoNL_NEW.png","width":2362,"height":515,"caption":"Stop Alzheimer"},"image":{"@id":"https:\/\/stopalzheimer.be\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/StichtingAlzheimerOnderzoek\/","https:\/\/www.youtube.com\/@stichtingalzheimeronderzoe3860\/videos","https:\/\/be.linkedin.com\/in\/stichting-alzheimer-onderzoek-fondation-recherche-alzheimer-8760b61a4"]},{"@type":"Person","@id":"https:\/\/stopalzheimer.be\/fr\/#\/schema\/person\/a4bfa7bb02bcf39e27ec3b315c293e22","name":"Lucie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a2cabf71da3f66ce28610368d66eab36ec2a054b07526e0376fc3565112668b7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2cabf71da3f66ce28610368d66eab36ec2a054b07526e0376fc3565112668b7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2cabf71da3f66ce28610368d66eab36ec2a054b07526e0376fc3565112668b7?s=96&d=mm&r=g","caption":"Lucie"},"url":"https:\/\/stopalzheimer.be\/fr\/author\/lucie\/"}]}},"_links":{"self":[{"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/posts\/4232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/comments?post=4232"}],"version-history":[{"count":20,"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/posts\/4232\/revisions"}],"predecessor-version":[{"id":6012,"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/posts\/4232\/revisions\/6012"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/media\/4234"}],"wp:attachment":[{"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/media?parent=4232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/categories?post=4232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/tags?post=4232"},{"taxonomy":"locatie","embeddable":true,"href":"https:\/\/stopalzheimer.be\/fr\/wp-json\/wp\/v2\/locatie?post=4232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}